{"id":4305,"date":"2022-08-28T12:20:00","date_gmt":"2022-08-28T18:20:00","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4305"},"modified":"2022-08-29T12:24:13","modified_gmt":"2022-08-29T18:24:13","slug":"imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/","title":{"rendered":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 28 de agosto de 2022<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">BOLET\u00cdN SESA 446\/22<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sensibiliza sobre los aspectos que fortalecen la salud mental, como medida preventiva de la ansiedad y depresi\u00f3n, as\u00ed como de los da\u00f1os que ocasiona el consumo de alcohol, tabaco y otras drogas.<br>Participan 60 empleados de las plantas de los municipios de Col\u00f3n y El Marqu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Salud (SESA) de Quer\u00e9taro informa que, a trav\u00e9s del Consejo Estatal contra las Adicciones (CECA), se imparti\u00f3 la conferencia en Prevenci\u00f3n de Adicciones y Salud Mental a 60 empleados de la empresa industrial PAS Appliance Systems SA de CV, en sus plantas de los municipios de Col\u00f3n y El Marqu\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo es sensibilizar al personal sobre los aspectos que fortalecen la salud mental, como medida preventiva sobre temas de ansiedad y depresi\u00f3n, as\u00ed como de los da\u00f1os que ocasiona el consumo de alcohol, tabaco y otras drogas, adem\u00e1s de los mitos y realidades que las rodean.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La importancia de la estrategia laboral radica en concientizar a cada uno de los trabajadores de que el consumo excesivo y la dependencia de alcohol y otras drogas, da\u00f1an de forma significativa su salud y calidad de vida y por consecuencia el rendimiento laboral; lo que a su vez se refleja en un impacto en la productividad de la empresa, causado, entre otros factores, por el ausentismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo anterior, es importante que se tome conciencia sobre la necesidad de continuar impulsando acciones de prevenci\u00f3n en los centros de trabajo, identificando, previniendo y, en su caso, atendiendo los factores de riesgo psicosocial laboral, que puedan estar contribuyendo al consumo de sustancias psicotr\u00f3picas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la capacitaci\u00f3n se analizaron los servicios que se brindan en los Centros de Atenci\u00f3n Primaria en Adicciones en donde se ofrecen servicios de prevenci\u00f3n y atenci\u00f3n de salud mental y adicciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sensibiliza sobre los aspectos que fortalecen la salud mental, como medida preventiva de la ansiedad y depresi\u00f3n, as\u00ed como de los da\u00f1os que ocasiona el consumo de alcohol, tabaco y otras drogas.<\/p>\n","protected":false},"author":1,"featured_media":4306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[175,220,187,65,204,215,216,218,217,57,219],"class_list":["post-4305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-capacitacion","tag-centros-de-atencion-primaria","tag-colon","tag-concientizar","tag-el-marques","tag-pas-appliance-systems-sa-de-cv","tag-prevencion-de-adicciones-y-salud-mental","tag-riesgo-psicosocial-laboral","tag-sensibilizar","tag-sesa","tag-sustancias-psicotropicas","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Sensibiliza sobre los aspectos que fortalecen la salud mental, como medida preventiva de la ansiedad y depresi\u00f3n, as\u00ed como de los da\u00f1os que ocasiona el consumo de alcohol, tabaco y otras drogas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-28T18:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-29T18:24:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"863\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS\",\"datePublished\":\"2022-08-28T18:20:00+00:00\",\"dateModified\":\"2022-08-29T18:24:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/\"},\"wordCount\":331,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1.jpeg\",\"keywords\":[\"Capacitaci\u00f3n\",\"Centros de Atenci\u00f3n Primaria\",\"Col\u00f3n\",\"CONCIENTIZAR\",\"El Marqu\u00e9s\",\"PAS Appliance Systems SA de CV\",\"Prevenci\u00f3n de Adicciones y Salud Mental\",\"Riesgo Psicosocial Laboral\",\"Sensibilizar\",\"SESA\",\"Sustancias Psicotr\u00f3picas\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/\",\"name\":\"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1.jpeg\",\"datePublished\":\"2022-08-28T18:20:00+00:00\",\"dateModified\":\"2022-08-29T18:24:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/1.jpeg\",\"width\":1600,\"height\":863},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/08\\\/28\\\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/","og_locale":"es_MX","og_type":"article","og_title":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO","og_description":"Sensibiliza sobre los aspectos que fortalecen la salud mental, como medida preventiva de la ansiedad y depresi\u00f3n, as\u00ed como de los da\u00f1os que ocasiona el consumo de alcohol, tabaco y otras drogas.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2022-08-28T18:20:00+00:00","article_modified_time":"2022-08-29T18:24:13+00:00","og_image":[{"width":1600,"height":863,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS","datePublished":"2022-08-28T18:20:00+00:00","dateModified":"2022-08-29T18:24:13+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/"},"wordCount":331,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg","keywords":["Capacitaci\u00f3n","Centros de Atenci\u00f3n Primaria","Col\u00f3n","CONCIENTIZAR","El Marqu\u00e9s","PAS Appliance Systems SA de CV","Prevenci\u00f3n de Adicciones y Salud Mental","Riesgo Psicosocial Laboral","Sensibilizar","SESA","Sustancias Psicotr\u00f3picas"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/","name":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg","datePublished":"2022-08-28T18:20:00+00:00","dateModified":"2022-08-29T18:24:13+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/08\/1.jpeg","width":1600,"height":863},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/08\/28\/imparte-sesa-conferencia-sobre-prevencion-de-adicciones-y-salud-mental-en-empresa-pas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Imparte SESA conferencia sobre prevenci\u00f3n de adicciones y salud mental en empresa PAS"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4305"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4306"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}