{"id":4423,"date":"2022-10-31T11:21:39","date_gmt":"2022-10-31T17:21:39","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4423"},"modified":"2022-10-31T11:23:24","modified_gmt":"2022-10-31T17:23:24","slug":"realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/","title":{"rendered":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo"},"content":{"rendered":"<p>Pedro Escobedo, Qro., 29 de octubre de 2022<\/p>\n<p>BOLET\u00cdN SESA 580\/22<\/p>\n<p style=\"text-align: justify;\"><strong>Participan 82 padres y madres de familia de la Secundaria \u00c1ngela Peralta de El Ahorcado.<\/strong><\/p>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro a trav\u00e9s de profesionales de las Salud del Consejo Estatal Contra las Adicciones (CECA), imparti\u00f3 la conferencia \u201cSe\u00f1ales de alerta sobre el consumo de sustancias en tus hijos\u201d, a 82 padres y madres de familia de la secundaria \u00c1ngela Peralta, de la comunidad El Ahorcado, del municipio de Pedro Escobedo.<\/p>\n<p style=\"text-align: justify;\">El objetivo es que los padres y madres de familia puedan detectar y prevenir un posible consumo de drogas legales o ilegales. Durante la conferencia se invit\u00f3 a los participantes a reflexionar sobre la responsabilidad de ser padre o madre, y de las cosas que hacer para que sus hijos puedan tener un desarrollo favorable.<\/p>\n<p style=\"text-align: justify;\">Se resalt\u00f3 el impulso que se debe dar a los factores protectores de la salud mental. Tambi\u00e9n se hizo hincapi\u00e9 en la importancia de tener un tiempo de calidad, cercan\u00eda y seguimiento con sus hijas e hijos para contrarrestar las largas jornadas de trabajo, y as\u00ed detectar cuando est\u00e9n en riesgo y ayudarlos cuando lo necesiten.<\/p>\n<p style=\"text-align: justify;\">Asimismo, se analiz\u00f3 la atenci\u00f3n que se ofrece en los Centros de Atenci\u00f3n Primaria en Adicciones con la finalidad de que solicite apoyo en caso necesario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pedro Escobedo, Qro., 29 de octubre de 2022 BOLET\u00cdN SESA 580\/22 Participan 82 padres y madres de familia de la Secundaria \u00c1ngela Peralta de El Ahorcado. La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro a trav\u00e9s de profesionales de las Salud del Consejo Estatal Contra las Adicciones (CECA), imparti\u00f3.<\/p>\n","protected":false},"author":1,"featured_media":4424,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[115,246,247,243,244,182,248,38,245,57],"class_list":["post-4423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-centros-de-atencion-primaria-en-adicciones","tag-consumo-de-sustancias","tag-hijos","tag-madres-de-familia","tag-padres-de-familia","tag-pedro-escobedo","tag-prevenir","tag-salud-mental","tag-senales-de-alerta","tag-sesa","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Pedro Escobedo, Qro., 29 de octubre de 2022 BOLET\u00cdN SESA 580\/22 Participan 82 padres y madres de familia de la Secundaria \u00c1ngela Peralta de El Ahorcado. La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro a trav\u00e9s de profesionales de las Salud del Consejo Estatal Contra las Adicciones (CECA), imparti\u00f3.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-31T17:21:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-31T17:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1523\" \/>\n\t<meta property=\"og:image:height\" content=\"752\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo\",\"datePublished\":\"2022-10-31T17:21:39+00:00\",\"dateModified\":\"2022-10-31T17:23:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/\"},\"wordCount\":238,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/1-1.jpeg\",\"keywords\":[\"Centros de Atenci\u00f3n Primaria en Adicciones\",\"Consumo de Sustancias\",\"Hijos\",\"Madres de familia\",\"Padres de familia\",\"Pedro Escobedo\",\"Prevenir\",\"SALUD MENTAL\",\"Se\u00f1ales de Alerta\",\"SESA\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/\",\"name\":\"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/1-1.jpeg\",\"datePublished\":\"2022-10-31T17:21:39+00:00\",\"dateModified\":\"2022-10-31T17:23:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/1-1.jpeg\",\"width\":1523,\"height\":752},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2022\\\/10\\\/31\\\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/","og_locale":"es_MX","og_type":"article","og_title":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO","og_description":"Pedro Escobedo, Qro., 29 de octubre de 2022 BOLET\u00cdN SESA 580\/22 Participan 82 padres y madres de familia de la Secundaria \u00c1ngela Peralta de El Ahorcado. La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro a trav\u00e9s de profesionales de las Salud del Consejo Estatal Contra las Adicciones (CECA), imparti\u00f3.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2022-10-31T17:21:39+00:00","article_modified_time":"2022-10-31T17:23:24+00:00","og_image":[{"width":1523,"height":752,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo","datePublished":"2022-10-31T17:21:39+00:00","dateModified":"2022-10-31T17:23:24+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/"},"wordCount":238,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg","keywords":["Centros de Atenci\u00f3n Primaria en Adicciones","Consumo de Sustancias","Hijos","Madres de familia","Padres de familia","Pedro Escobedo","Prevenir","SALUD MENTAL","Se\u00f1ales de Alerta","SESA"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/","name":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg","datePublished":"2022-10-31T17:21:39+00:00","dateModified":"2022-10-31T17:23:24+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2022\/10\/1-1.jpeg","width":1523,"height":752},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2022\/10\/31\/realiza-sesa-conferencia-de-prevencion-de-adicciones-en-pedro-escobedo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Realiza SESA conferencia de Prevenci\u00f3n de Adicciones en Pedro Escobedo"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4423"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4424"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}