{"id":4480,"date":"2023-01-29T11:48:36","date_gmt":"2023-01-29T17:48:36","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4480"},"modified":"2023-01-30T11:56:15","modified_gmt":"2023-01-30T17:56:15","slug":"lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/","title":{"rendered":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral"},"content":{"rendered":"<p>Quer\u00e9taro, Qro., 29 de enero de 2023<\/p>\n<p>BOLET\u00cdN SESA 034\/23<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Participaron 148 trabajadores de la empresa Brose extensi\u00f3n Vie Verte.<\/strong><\/p>\n<p>La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro informa que, a trav\u00e9s del Consejo Estatal Contra las Adicciones (CECA), imparti\u00f3 de manera virtual la conferencia en prevenci\u00f3n de adicciones y cuidado de la salud mental a 148 trabajadoras y trabajadores de la empresa Brose extensi\u00f3n Vie Verte.<\/p>\n<p>Para realizar el trabajo a plenitud deben existir recursos, destrezas y, de forma principal, la salud y bienestar en quienes integran una empresa. El consumo de drogas afecta el rendimiento de las personas, exponi\u00e9ndolas a accidentes, enfermedades, p\u00e9rdida del empleo, deudas y exclusi\u00f3n social. Las organizaciones tambi\u00e9n se ven afectadas en sus procesos productivos por ausentismo, incapacidades o conflictos.<\/p>\n<p>Por ello es relevante incluir en la estrategia laboral el concientizar a cada uno de los trabajadores de que el consumo excesivo y la dependencia de alcohol y otras drogas, da\u00f1an de forma significativa su salud y calidad de vida y por consecuencia el rendimiento laboral.<\/p>\n<p>Ante esta situaci\u00f3n, es importante tener informaci\u00f3n veraz sobre las adicciones, sus efectos y la manera de prevenirlas. Dentro de la capacitaci\u00f3n se dej\u00f3 claro que el alcohol y el tabaco son drogas legales que producen significativas alteraciones en el sistema nervioso central: el alcohol es un depresor, y el tabaco es un estimulante. Adem\u00e1s perjudican a otros tejidos y \u00f3rganos del cuerpo (h\u00edgado, pulmones). Su consumo reiterado genera dependencia.<\/p>\n<p>Se resaltaron las situaciones que ponen en riesgo a una persona y las que la protegen a trav\u00e9s de la salud mental ya que las preparan para enfrentar adecuadamente los problemas. As\u00ed como la importancia de conocer las fortalezas, mantenerse informados y sumar esfuerzos para promover estilos de vida m\u00e1s saludables en su entorno.<\/p>\n<p>Al t\u00e9rmino de la capacitaci\u00f3n se pusieron a disposici\u00f3n los servicios que se brindan en los Centros de Atenci\u00f3n Primaria en Adicciones, en donde se ofrecen servicios de prevenci\u00f3n y atenci\u00f3n de salud mental y adicciones para los trabajadores y sus familias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participaron 148 trabajadores de la empresa Brose extensi\u00f3n Vie Verte.<\/p>\n","protected":false},"author":1,"featured_media":4484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[37,287,65,289,34,288,57],"class_list":["post-4480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-adicciones","tag-ambito-laboral","tag-concientizar","tag-efectos","tag-prevencion","tag-salud-y-bienestar","tag-sesa","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Participaron 148 trabajadores de la empresa Brose extensi\u00f3n Vie Verte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-29T17:48:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-30T17:56:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1266\" \/>\n\t<meta property=\"og:image:height\" content=\"646\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral\",\"datePublished\":\"2023-01-29T17:48:36+00:00\",\"dateModified\":\"2023-01-30T17:56:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/\"},\"wordCount\":376,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cap-Brose.jpeg\",\"keywords\":[\"ADICCIONES\",\"\u00c1mbito Laboral\",\"CONCIENTIZAR\",\"Efectos\",\"PREVENCI\u00d3N\",\"Salud y Bienestar\",\"SESA\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/\",\"name\":\"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cap-Brose.jpeg\",\"datePublished\":\"2023-01-29T17:48:36+00:00\",\"dateModified\":\"2023-01-30T17:56:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cap-Brose.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Cap-Brose.jpeg\",\"width\":1266,\"height\":646},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/01\\\/29\\\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/","og_locale":"es_MX","og_type":"article","og_title":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO","og_description":"Participaron 148 trabajadores de la empresa Brose extensi\u00f3n Vie Verte.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-01-29T17:48:36+00:00","article_modified_time":"2023-01-30T17:56:15+00:00","og_image":[{"width":1266,"height":646,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral","datePublished":"2023-01-29T17:48:36+00:00","dateModified":"2023-01-30T17:56:15+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/"},"wordCount":376,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg","keywords":["ADICCIONES","\u00c1mbito Laboral","CONCIENTIZAR","Efectos","PREVENCI\u00d3N","Salud y Bienestar","SESA"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/","name":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg","datePublished":"2023-01-29T17:48:36+00:00","dateModified":"2023-01-30T17:56:15+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/01\/Cap-Brose.jpeg","width":1266,"height":646},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/01\/29\/lleva-sesa-prevencion-de-adicciones-y-cuidado-de-la-salud-mental-al-ambito-laboral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Lleva SESA Prevenci\u00f3n de Adicciones y Cuidado de la Salud Mental al \u00e1mbito laboral"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4480"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4484"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}