{"id":4597,"date":"2023-03-16T10:11:23","date_gmt":"2023-03-16T16:11:23","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4597"},"modified":"2023-03-16T10:11:23","modified_gmt":"2023-03-16T16:11:23","slug":"capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/","title":{"rendered":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda"},"content":{"rendered":"<p style=\"text-align: justify;\">Quer\u00e9taro, Qro., 15 de marzo de 2023<\/p>\n<p style=\"text-align: justify;\">BOLET\u00cdN SESA 131\/23<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Participaron 27 mujeres y 47 hombres de los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan.<\/strong><\/p>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, informa que a trav\u00e9s del Consejo Estatal Contra las Adicciones (CECA), se capacit\u00f3 en Manejo y Control de Intoxicaci\u00f3n Aguda a 27 mujeres y 47 hombres (74) entre personal de \u00e1rea m\u00e9dica y responsables de los Establecimientos Residenciales de Atenci\u00f3n a las Adicciones.<\/p>\n<p style=\"text-align: justify;\">El objetivo es que las y los responsables de los centros de rehabilitaci\u00f3n cuenten con la capacidad para brindar un servicio de atenci\u00f3n integral, digno y humano; as\u00ed como abordar el manejo y control de intoxicaci\u00f3n aguda y s\u00edndrome de abstinencia en usuarios de sustancias psicoactivas que ingresen a rehabilitaci\u00f3n.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4599\" src=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1.jpeg\" alt=\"\" width=\"1599\" height=\"535\" srcset=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1.jpeg 1599w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-300x100.jpeg 300w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-1024x343.jpeg 1024w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-768x257.jpeg 768w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-1536x514.jpeg 1536w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-570x191.jpeg 570w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/2-1-270x90.jpeg 270w\" sizes=\"(max-width: 1599px) 100vw, 1599px\" \/><\/p>\n<p style=\"text-align: justify;\">Los temas que se analizaron fueron: Manejo y control de intoxicaci\u00f3n aguda; Manejo y control del s\u00edndrome de abstinencia; Protocolo y derivaci\u00f3n de pacientes que presentan urgencias en salud que exceden la capacidad de resoluci\u00f3n local.<\/p>\n<p style=\"text-align: justify;\">Cabe se\u00f1alar que la capacitaci\u00f3n se llev\u00f3 a cabo en el Auditorio del Hospital General de Quer\u00e9taro y fue impartida por Ana Romina Montane Ba\u00f1os. Los asistentes brindan atenci\u00f3n en establecimientos ubicados en los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participaron 27 mujeres y 47 hombres de los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan.<\/p>\n","protected":false},"author":1,"featured_media":4598,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[316,175,315,317,318],"class_list":["post-4597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-atencion-a-las-adicciones","tag-capacitacion","tag-manejo-y-control-de-intoxicacion-aguda","tag-manejo-y-control-del-sindrome-de-abstinencia","tag-protocolo-y-derivacion-de-pacientes","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Participaron 27 mujeres y 47 hombres de los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-16T16:11:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1046\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda\",\"datePublished\":\"2023-03-16T16:11:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/\"},\"wordCount\":252,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-1.jpeg\",\"keywords\":[\"Atenci\u00f3n a las Adicciones\",\"Capacitaci\u00f3n\",\"Manejo y Control de Intoxicaci\u00f3n Aguda\",\"Manejo y control del s\u00edndrome de abstinencia\",\"Protocolo y derivaci\u00f3n de pacientes\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/\",\"name\":\"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-1.jpeg\",\"datePublished\":\"2023-03-16T16:11:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/1-1.jpeg\",\"width\":1600,\"height\":1046},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/03\\\/16\\\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/","og_locale":"es_MX","og_type":"article","og_title":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO","og_description":"Participaron 27 mujeres y 47 hombres de los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-03-16T16:11:23+00:00","og_image":[{"width":1600,"height":1046,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda","datePublished":"2023-03-16T16:11:23+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/"},"wordCount":252,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg","keywords":["Atenci\u00f3n a las Adicciones","Capacitaci\u00f3n","Manejo y Control de Intoxicaci\u00f3n Aguda","Manejo y control del s\u00edndrome de abstinencia","Protocolo y derivaci\u00f3n de pacientes"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/","name":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg","datePublished":"2023-03-16T16:11:23+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/03\/1-1.jpeg","width":1600,"height":1046},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/03\/16\/capacita-sesa-a-personal-de-establecimientos-en-manejo-y-control-de-intoxicacion-aguda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Capacita SESA a personal de establecimientos en Manejo y Control de Intoxicaci\u00f3n Aguda"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4597"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4598"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}