{"id":4657,"date":"2023-04-27T12:25:07","date_gmt":"2023-04-27T18:25:07","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4657"},"modified":"2023-04-28T12:28:21","modified_gmt":"2023-04-28T18:28:21","slug":"premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/","title":{"rendered":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones"},"content":{"rendered":"<p>Quer\u00e9taro, Qro., 27 de abril de 2023<\/p>\n<p>BOLET\u00cdN SESA 226\/23<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El objetivo es prevenir adicciones y reconocer los factores de protecci\u00f3n de la salud mental, a trav\u00e9s de la expresi\u00f3n creativa de las ni\u00f1as, ni\u00f1os y adolescentes de 10 a 12 a\u00f1os.<\/strong><\/p>\n<p>Los tres primeros lugares son del municipio de San Juan del R\u00edo, y las menciones honor\u00edficas de los municipios de San Joaqu\u00edn y Quer\u00e9taro.<\/p>\n<p>La secretaria de Salud, Mar\u00eda Martina P\u00e9rez Rend\u00f3n, encabez\u00f3 la ceremonia de premiaci\u00f3n de las y los ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones \u201cMe quiero, me cuido y soy feliz\u201d, que estuvo coordinado por el Consejo Estatal contra las Adicciones (CECA), y que tuvo como objetivo promover la prevenci\u00f3n de adicciones y reconocer los factores de protecci\u00f3n de la salud mental a trav\u00e9s de la expresi\u00f3n creativa de las y los ni\u00f1os y adolescentes de 10 a 12 a\u00f1os.<\/p>\n<p>La titular de Salud, destac\u00f3 que a trav\u00e9s de sinergias se trabaja en la prevenci\u00f3n de las adicciones, y reconoci\u00f3 que hay grandes aliados en el estado como son las Instituciones y los Comit\u00e9s Municipales contra las Adicciones (COMCA).<\/p>\n<p>Subray\u00f3 que desde la Secretar\u00eda de Salud (SESA) se impulsa la prevenci\u00f3n, y en este concurso se observa que las ni\u00f1as y ni\u00f1os identifican bien cu\u00e1les son los factores protectores de la salud mental.<\/p>\n<p>\u201cTrabajar con la ni\u00f1ez queretana, ni\u00f1os hablando con ni\u00f1as, ni\u00f1os presentando lo que identifican como factor protector y el riesgo en el que pueden estar, nos ayudan a ser promotores de la salud\u201d, comparti\u00f3 la Secretaria.<\/p>\n<p>El Comisionado del CECA, Andr\u00e9s Longoria Aguilar recalc\u00f3 la importancia de visibilizar los factores de protecci\u00f3n como son las actividades deportivas, culturales, de esparcimiento y desarrollo que ayudan a vivir en plenitud y a un desarrollo de la mejor manera.<\/p>\n<p>Asimismo, la coordinadora del Centro de Asistencia Social Carmelita Ballesteros, Valentina Rolland Ru\u00edz, calific\u00f3 como excelente la iniciativa de realizar a\u00f1o con a\u00f1o un concurso de dibujo.<\/p>\n<p>\u201cDin\u00e1micas as\u00ed son importantes en nuestra sociedad ya que a trav\u00e9s de ejercicios como estos podemos reflexionar y tomar consciencia sobre la problem\u00e1tica de adicciones\u201d, coincidi\u00f3.<\/p>\n<p>El primer lugar fue para Jimena Pi\u00f1a M\u00e1rquez, de 12 a\u00f1os de edad, estudiante del primer a\u00f1o en la Secundaria Antonio Caso de San Juan del R\u00edo; el segundo lugar fue para Alejandro Gonz\u00e1lez Becerril, de 11 a\u00f1os de edad, del sexto grado en la Primaria M\u00e1rtir de Chihuahua, de San Juan del R\u00edo. En tercer lugar, Camila Michelle Garc\u00eda Garc\u00eda, de 11 a\u00f1os de edad, quien cursa el sexto grado en la Primaria Daniel Ortiz Esquivel, de San Juan del R\u00edo.<\/p>\n<p>Se entregaron menciones honor\u00edficas para Karime S\u00e1nchez Ledesma, de 11 a\u00f1os de edad, quien cursa el sexto grado en la primaria A\u00f1o de Hidalgo, en el municipio de San Joaqu\u00edn y para Caleb Alexander Nieves Garc\u00eda, de 10 a\u00f1os de edad, que cursa el quinto grado en la Primaria 21 de Marzo, en el municipio de Quer\u00e9taro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo es prevenir adicciones y reconocer los factores de protecci\u00f3n de la salud mental, a trav\u00e9s de la expresi\u00f3n creativa de las ni\u00f1as, ni\u00f1os y adolescentes de 10 a 12 a\u00f1os.<\/p>\n","protected":false},"author":1,"featured_media":4658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[267,146,331,147,302],"class_list":["post-4657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-comites-municipales-contra-las-adicciones","tag-concurso-estatal-de-dibujo-infantil","tag-ninez","tag-premiacion","tag-prevencion-de-adicciones","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"El objetivo es prevenir adicciones y reconocer los factores de protecci\u00f3n de la salud mental, a trav\u00e9s de la expresi\u00f3n creativa de las ni\u00f1as, ni\u00f1os y adolescentes de 10 a 12 a\u00f1os.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T18:25:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T18:28:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1127\" \/>\n\t<meta property=\"og:image:height\" content=\"714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones\",\"datePublished\":\"2023-04-27T18:25:07+00:00\",\"dateModified\":\"2023-04-28T18:28:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/\"},\"wordCount\":552,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"keywords\":[\"Comit\u00e9s Municipales Contra las Adicciones\",\"Concurso Estatal de Dibujo Infantil\",\"Ni\u00f1ez\",\"Premiaci\u00f3n\",\"Prevenci\u00f3n de Adicciones\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/\",\"name\":\"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"datePublished\":\"2023-04-27T18:25:07+00:00\",\"dateModified\":\"2023-04-28T18:28:21+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/3.jpg\",\"width\":1127,\"height\":714},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/04\\\/27\\\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/","og_locale":"es_MX","og_type":"article","og_title":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO","og_description":"El objetivo es prevenir adicciones y reconocer los factores de protecci\u00f3n de la salud mental, a trav\u00e9s de la expresi\u00f3n creativa de las ni\u00f1as, ni\u00f1os y adolescentes de 10 a 12 a\u00f1os.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-04-27T18:25:07+00:00","article_modified_time":"2023-04-28T18:28:21+00:00","og_image":[{"width":1127,"height":714,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones","datePublished":"2023-04-27T18:25:07+00:00","dateModified":"2023-04-28T18:28:21+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/"},"wordCount":552,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg","keywords":["Comit\u00e9s Municipales Contra las Adicciones","Concurso Estatal de Dibujo Infantil","Ni\u00f1ez","Premiaci\u00f3n","Prevenci\u00f3n de Adicciones"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/","name":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg","datePublished":"2023-04-27T18:25:07+00:00","dateModified":"2023-04-28T18:28:21+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/04\/3.jpg","width":1127,"height":714},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/04\/27\/premia-sesa-a-ganadores-del-concurso-estatal-de-dibujo-infantil-prevenimos-adicciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Premia SESA a ganadores del Concurso Estatal de Dibujo Infantil Prevenimos Adicciones"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4657"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4658"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}