{"id":4740,"date":"2023-06-03T12:45:35","date_gmt":"2023-06-03T18:45:35","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4740"},"modified":"2023-06-05T12:50:28","modified_gmt":"2023-06-05T18:50:28","slug":"realiza-sesa-colillaton-2023","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/","title":{"rendered":"Realiza SESA Colillat\u00f3n 2023"},"content":{"rendered":"<p style=\"text-align: justify;\">Quer\u00e9taro, Qro., 3 de junio de 2023<\/p>\n<p style=\"text-align: justify;\">BOLET\u00cdN SESA 296\/23<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Se busca promover el cuidado de la salud, fortalecer factores de protecci\u00f3n y acciones que fomenten el cuidado del medio ambiente.<\/strong><br \/>\nUn total de 15 mil 840 colillas de cigarros se recogieron, lo que lo que representa proteger de ser contaminados 205 mil 920 litros de agua salada y 792 mil litros de agua potable.<\/p>\n<p style=\"text-align: justify;\">La secretaria de Salud (SESA) del estado de Quer\u00e9taro, Mar\u00eda Martina P\u00e9rez Rend\u00f3n, en el marco del D\u00eda Mundial Sin Tabaco, conmemorado el pasado 31 mayo, encabez\u00f3 el Colillat\u00f3n 2023 en el jard\u00edn de La Corregidora, la cual tuvo como objetivo el promover el cuidado de la salud, fortalecer factores de protecci\u00f3n y acciones que fomenten el cuidado del medio ambiente.<\/p>\n<p style=\"text-align: justify;\">P\u00e9rez Rend\u00f3n, destac\u00f3 que el Colillat\u00f3n es mucho m\u00e1s que una simple campa\u00f1a de recoger colillas, sino dijo, se trata de un llamado a la acci\u00f3n colectiva a favor del cuidado del medio ambiente y de la salud. Destac\u00f3 que el trabajo que cada uno de las y los voluntarios desempe\u00f1\u00f3, demostr\u00f3 el compromiso inquebrantable en la protecci\u00f3n del entorno.<\/p>\n<p style=\"text-align: justify;\">\u201cDurante este ejercicio hemos sido testigos de la fuerza transformadora que surge cuando nos unimos por una causa com\u00fan. Juntos recogimos 15 mil 840 colillas, evitando que contaminen nuestros ecosistemas, adem\u00e1s del gran ejemplo que se dio a la sociedad\u201d, dijo.<\/p>\n<p style=\"text-align: justify;\">Asimismo, resalt\u00f3 que con esta actividad se inicia un camino para un futuro sostenible, en el cual debemos continuar trabajando juntos, promoviendo pr\u00e1cticas responsables, fomentando la educaci\u00f3n ambiental y buscando soluciones innovadoras para proteger y preservar nuestro entorno. Han demostrado que cuando la sociedad se une los resultados son extraordinarios. Sigamos trabajando para un mundo m\u00e1s verde, sostenible y saludable para las generaciones futuras.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-4742\" src=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296.jpg\" alt=\"\" width=\"1500\" height=\"565\" srcset=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296.jpg 1500w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296-300x113.jpg 300w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296-1024x386.jpg 1024w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296-768x289.jpg 768w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296-570x215.jpg 570w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296-270x102.jpg 270w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/><\/p>\n<p style=\"text-align: justify;\">En su intervenci\u00f3n, el comisionado del Centro Estatal Contra las Adicciones (CECA), Andr\u00e9s Longoria Aguilar, detall\u00f3 que en una hora y media se recolectaron seis kilos 600 gramos de colillas, lo que representa proteger de ser contaminados 205 mil 920 litros de agua salada y 792 mil litros de agua potable. Adem\u00e1s, subray\u00f3 que el humo de tabaco tambi\u00e9n tiene un gran impacto a la salud de la sociedad.<\/p>\n<p style=\"text-align: justify;\">Se cont\u00f3 con la participaci\u00f3n de 120 voluntarios, 40 mujeres y 80 hombres, del grupo \u201cVoluntadEs\u201d del CECA, -integrado por pacientes que concluyeron su tratamiento en alg\u00fan Centro de Rehabilitaci\u00f3n-; de la Secretar\u00eda de Desarrollo Social, y Punto Org\u00e1nico, quienes organizados en grupos recorrieron las cuatro rutas de: Plaza del Estudiante, Distrito Alameda, Mirador de los Arcos y Mercado de la Cruz.<\/p>\n<p style=\"text-align: justify;\">De manera simult\u00e1nea, los Comit\u00e9s Municipales contra las Adicciones de Col\u00f3n, Tolim\u00e1n, San Joaqu\u00edn, Corregidora, Cadereyta, San Juan del R\u00edo y El Centro Vive El Marqu\u00e9s, realizaron su recolecci\u00f3n de colillas y llevaron diversas conferencias de los da\u00f1os que ocasiona el tabaco a estudiantes de Secundaria y Preparatoria.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Se busca promover el cuidado de la salud, fortalecer factores de protecci\u00f3n y acciones que fomenten el cuidado del medio ambiente.<\/p>\n","protected":false},"author":1,"featured_media":4741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[350,348,349],"class_list":["post-4740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-colillas-de-cigarros","tag-colillaton-2023","tag-voluntades","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Se busca promover el cuidado de la salud, fortalecer factores de protecci\u00f3n y acciones que fomenten el cuidado del medio ambiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-03T18:45:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T18:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1237\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Realiza SESA Colillat\u00f3n 2023\",\"datePublished\":\"2023-06-03T18:45:35+00:00\",\"dateModified\":\"2023-06-05T18:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/\"},\"wordCount\":496,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/296a.jpg\",\"keywords\":[\"Colillas de cigarros\",\"Colillat\u00f3n 2023\",\"VoluntadEs\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/\",\"name\":\"Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/296a.jpg\",\"datePublished\":\"2023-06-03T18:45:35+00:00\",\"dateModified\":\"2023-06-05T18:50:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/296a.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/296a.jpg\",\"width\":1500,\"height\":1237},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/03\\\/realiza-sesa-colillaton-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realiza SESA Colillat\u00f3n 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/","og_locale":"es_MX","og_type":"article","og_title":"Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO","og_description":"Se busca promover el cuidado de la salud, fortalecer factores de protecci\u00f3n y acciones que fomenten el cuidado del medio ambiente.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-06-03T18:45:35+00:00","article_modified_time":"2023-06-05T18:50:28+00:00","og_image":[{"width":1500,"height":1237,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Realiza SESA Colillat\u00f3n 2023","datePublished":"2023-06-03T18:45:35+00:00","dateModified":"2023-06-05T18:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/"},"wordCount":496,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg","keywords":["Colillas de cigarros","Colillat\u00f3n 2023","VoluntadEs"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/","name":"Realiza SESA Colillat\u00f3n 2023 - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg","datePublished":"2023-06-03T18:45:35+00:00","dateModified":"2023-06-05T18:50:28+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/296a.jpg","width":1500,"height":1237},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/03\/realiza-sesa-colillaton-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Realiza SESA Colillat\u00f3n 2023"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4740"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4740\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4741"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}