{"id":4752,"date":"2023-06-09T12:40:14","date_gmt":"2023-06-09T18:40:14","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4752"},"modified":"2023-06-13T12:44:23","modified_gmt":"2023-06-13T18:44:23","slug":"suspenden-autoridades-centro-de-rehabilitacion-en-queretaro","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/","title":{"rendered":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro"},"content":{"rendered":"<p>Quer\u00e9taro, Qro., 9 de junio de 2023<\/p>\n<p>BOLET\u00cdN SESA 307\/23<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">La Secretar\u00eda de Salud (SESA) del Estado informa que a solicitud de la Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro, el Comit\u00e9 Estatal para la Supervisi\u00f3n de Establecimientos Residenciales Especializados en Adicciones, realiz\u00f3 una visita de verificaci\u00f3n al Centro de Rehabilitaci\u00f3n \u201cRenacimiento 24 horas\u201d, ubicado en el municipio de Quer\u00e9taro. Al detectar una serie de anomal\u00edas se procedi\u00f3 a la suspensi\u00f3n de actividades.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-4754 alignleft\" src=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/sello-proteccion-civil-3.jpg\" alt=\"\" width=\"384\" height=\"256\" srcset=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/sello-proteccion-civil-3.jpg 384w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/sello-proteccion-civil-3-300x200.jpg 300w, https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/sello-proteccion-civil-3-270x180.jpg 270w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><\/p>\n<p style=\"text-align: justify;\">Entre las anomal\u00edas que se encontraron fue el no contar con Aviso de Funcionamiento, sin Licencia municipal y sin dictamen de Protecci\u00f3n Civil, motivo por lo cual se procedi\u00f3 a la sanci\u00f3n por parte de la Direcci\u00f3n de Protecci\u00f3n contra Riesgos Sanitarios de la Secretar\u00eda de Salud y de la Coordinaci\u00f3n Municipal de Protecci\u00f3n Civil.<\/p>\n<p style=\"text-align: justify;\">En dicho centro se encontraban 23 pacientes internos, de los cuales 20 decidieron regresar a casa con su familia y tres quisieron ser reubicados en otro establecimiento por lo que fueron apoyados por el Consejo Estatal Contra las Adicciones (CECA) para el traslado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 9 de junio de 2023 BOLET\u00cdN SESA 307\/23 &nbsp; La Secretar\u00eda de Salud (SESA) del Estado informa que a solicitud de la Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro, el Comit\u00e9 Estatal para la Supervisi\u00f3n de Establecimientos Residenciales Especializados en Adicciones, realiz\u00f3 una visita de verificaci\u00f3n al Centro.<\/p>\n","protected":false},"author":1,"featured_media":4753,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[354,202,355],"class_list":["post-4752","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-centro-de-rehabilitacion","tag-defensoria-de-los-derechos-humanos-de-queretaro","tag-suspencion","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 9 de junio de 2023 BOLET\u00cdN SESA 307\/23 &nbsp; La Secretar\u00eda de Salud (SESA) del Estado informa que a solicitud de la Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro, el Comit\u00e9 Estatal para la Supervisi\u00f3n de Establecimientos Residenciales Especializados en Adicciones, realiz\u00f3 una visita de verificaci\u00f3n al Centro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-09T18:40:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-13T18:44:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"384\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro\",\"datePublished\":\"2023-06-09T18:40:14+00:00\",\"dateModified\":\"2023-06-13T18:44:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/\"},\"wordCount\":194,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Sello-Regulacion-Sanitaria-2.jpg\",\"keywords\":[\"Centro de Rehabilitaci\u00f3n\",\"Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro\",\"Suspenci\u00f3n\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/\",\"name\":\"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Sello-Regulacion-Sanitaria-2.jpg\",\"datePublished\":\"2023-06-09T18:40:14+00:00\",\"dateModified\":\"2023-06-13T18:44:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Sello-Regulacion-Sanitaria-2.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Sello-Regulacion-Sanitaria-2.jpg\",\"width\":384,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/06\\\/09\\\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/","og_locale":"es_MX","og_type":"article","og_title":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 9 de junio de 2023 BOLET\u00cdN SESA 307\/23 &nbsp; La Secretar\u00eda de Salud (SESA) del Estado informa que a solicitud de la Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro, el Comit\u00e9 Estatal para la Supervisi\u00f3n de Establecimientos Residenciales Especializados en Adicciones, realiz\u00f3 una visita de verificaci\u00f3n al Centro.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-06-09T18:40:14+00:00","article_modified_time":"2023-06-13T18:44:23+00:00","og_image":[{"width":384,"height":256,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro","datePublished":"2023-06-09T18:40:14+00:00","dateModified":"2023-06-13T18:44:23+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/"},"wordCount":194,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg","keywords":["Centro de Rehabilitaci\u00f3n","Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro","Suspenci\u00f3n"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/","name":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg","datePublished":"2023-06-09T18:40:14+00:00","dateModified":"2023-06-13T18:44:23+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/06\/Sello-Regulacion-Sanitaria-2.jpg","width":384,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/06\/09\/suspenden-autoridades-centro-de-rehabilitacion-en-queretaro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Suspenden autoridades Centro de Rehabilitaci\u00f3n en Quer\u00e9taro"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4752","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4752"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4752\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4753"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4752"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4752"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4752"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}