{"id":4839,"date":"2023-07-18T11:46:45","date_gmt":"2023-07-18T17:46:45","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=4839"},"modified":"2023-07-24T11:50:44","modified_gmt":"2023-07-24T17:50:44","slug":"capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/","title":{"rendered":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX"},"content":{"rendered":"<p>Quer\u00e9taro, Qro., 18 de julio de 2023<\/p>\n<p>BOLET\u00cdN SESA 368\/23<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Se benefici\u00f3 a un total de 77 empleados, 10 mujeres y 67 hombres.<\/strong><\/p>\n<p>Personal del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, llev\u00f3 a cabo capacitaci\u00f3n con el tema de Prevenci\u00f3n de Adicciones a 77 empleados, 10 mujeres y 67 hombres de la empresa CONDUMEX, ubicada en el Parque Industrial Jurica, en el municipio de Quer\u00e9taro.<\/p>\n<p>El tema de la conferencia fue &#8220;Da\u00f1os a la salud que ocasiona el fumar y vapear&#8221;, con la que se inform\u00f3 a los asistentes que la mitad de los fumadores actuales, podr\u00edan morir por una enfermedad derivada del consumo de tabaco; por lo que es una de las causas de siete millones de muertes al a\u00f1o a nivel mundial, de las cuales casi un mill\u00f3n corresponden a personas que nunca fumaron, y que conviv\u00edan con fumadores activos. De ah\u00ed radica la importancia de dejar de fumar y de tener espacios libres de humo de tabaco y emisiones (ELHTYE).<\/p>\n<p>Referente a los beneficios de los ELHTYE se destac\u00f3 que evitan qu\u00e9 las y los j\u00f3venes empiecen a fumar, reducen el riesgo de incendios, disminuye la aceptaci\u00f3n social de fumar, restringe las faltas por enfermedades, ayudan a los fumadores a fumar menos y\/o a dejar de fumar, aumenta la productividad y satisfacci\u00f3n de las personas y evita el deterioro de las instalaciones de las \u00e1reas de trabajo, entre otras.<\/p>\n<p>Finalmente se ofreci\u00f3 la ayuda para dejar de fumar, de vapear, de consumir cualquier otra droga y atenci\u00f3n a la salud mental, que brindan los seis Centros Comunitarios de Salud Mental y Adicciones (CECOSAMA) que hay en el estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se benefici\u00f3 a un total de 77 empleados, 10 mujeres y 67 hombres.<\/p>\n","protected":false},"author":1,"featured_media":4840,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[360,302,359],"class_list":["post-4839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-condumex","tag-prevencion-de-adicciones","tag-vaping","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Se benefici\u00f3 a un total de 77 empleados, 10 mujeres y 67 hombres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T17:46:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T17:50:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"824\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX\",\"datePublished\":\"2023-07-18T17:46:45+00:00\",\"dateModified\":\"2023-07-24T17:50:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/\"},\"wordCount\":303,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/condumex-3.jpeg\",\"keywords\":[\"CONDUMEX\",\"Prevenci\u00f3n de Adicciones\",\"Vaping\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/\",\"name\":\"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/condumex-3.jpeg\",\"datePublished\":\"2023-07-18T17:46:45+00:00\",\"dateModified\":\"2023-07-24T17:50:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/condumex-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/condumex-3.jpeg\",\"width\":1600,\"height\":824},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2023\\\/07\\\/18\\\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/","og_locale":"es_MX","og_type":"article","og_title":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO","og_description":"Se benefici\u00f3 a un total de 77 empleados, 10 mujeres y 67 hombres.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2023-07-18T17:46:45+00:00","article_modified_time":"2023-07-24T17:50:44+00:00","og_image":[{"width":1600,"height":824,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX","datePublished":"2023-07-18T17:46:45+00:00","dateModified":"2023-07-24T17:50:44+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/"},"wordCount":303,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg","keywords":["CONDUMEX","Prevenci\u00f3n de Adicciones","Vaping"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/","name":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg","datePublished":"2023-07-18T17:46:45+00:00","dateModified":"2023-07-24T17:50:44+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2023\/07\/condumex-3.jpeg","width":1600,"height":824},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2023\/07\/18\/capacita-sesa-en-prevencion-de-adicciones-a-trabajadores-de-la-empresa-condumex\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Capacita SESA en prevenci\u00f3n de adicciones a trabajadores de la empresa CONDUMEX"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=4839"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/4839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/4840"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=4839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=4839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=4839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}