{"id":5338,"date":"2024-06-13T11:59:27","date_gmt":"2024-06-13T17:59:27","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5338"},"modified":"2024-06-14T12:04:44","modified_gmt":"2024-06-14T18:04:44","slug":"sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/","title":{"rendered":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span style=\"font-family: Avenir; font-size: 11px; text-align: right; white-space-collapse: collapse; color: initial;\">Quer\u00e9taro, Qro., 13 de junio de 2024<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se realizaron diversas actividades a favor de la salud de los 330 trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, reconoci\u00f3 a la Empresa ACPS Automotive, como empresa 100 % responsable en la prevenci\u00f3n de adicciones y cuidado de la salud mental y por ser un espacio libre de humo de tabaco y emisiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje, el comisionado del CECA, Adolfo R\u00edos M\u00e9ndez, destac\u00f3 que el objetivo de este reconocimiento es que las empresas p\u00fablicas o privadas fomenten la cultura de la prevenci\u00f3n de adicciones y salud mental, y un impacto social positivo en el \u00e1rea de trabajo y en la vida privada de las y los trabajadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el acto, el director general de ACPS Automotive, Fabi\u00e1n Sosa Andrade, enfatiz\u00f3 que como organizaci\u00f3n se apegan a un liderazgo responsable y este se segmenta en tres impactos: el impacto econ\u00f3mico, ambiental, y el m\u00e1s importante, el impacto social que es de los m\u00e1s gratificantes para la empresa, en resumen, apoyar en temas de salud y de estabilidad emocional de todos los colaboradores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las actividades sensibilizaron a un total de 330 trabajadores. Para ello se impartieron cursos psicoeducativos de salud mental y adicciones, informaci\u00f3n sobre los da\u00f1os que ocasiona el consumo de tabaco y el ABC de las drogas; asimismo participaron en la feria de salud y atenci\u00f3n psicol\u00f3gica que se llev\u00f3 a cabo en las instalaciones.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al evento tambi\u00e9n asisti\u00f3 el responsable de recursos Humanos, Adalberto P\u00e9rez Moreno y la responsable de Enfermer\u00eda, Paola Luna Gonz\u00e1lez, entre otras personalidades.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 13 de junio de 2024 Se realizaron diversas actividades a favor de la salud de los 330 trabajadores. El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, reconoci\u00f3 a la Empresa ACPS Automotive, como empresa 100 % responsable en la.<\/p>\n","protected":false},"author":1,"featured_media":5337,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"[]"},"categories":[33],"tags":[397,216],"class_list":["post-5338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-certificacion","tag-prevencion-de-adicciones-y-salud-mental","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 13 de junio de 2024 Se realizaron diversas actividades a favor de la salud de los 330 trabajadores. El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, reconoci\u00f3 a la Empresa ACPS Automotive, como empresa 100 % responsable en la.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-13T17:59:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-14T18:04:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental\",\"datePublished\":\"2024-06-13T17:59:27+00:00\",\"dateModified\":\"2024-06-14T18:04:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/\"},\"wordCount\":301,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/certi13jun.jpg\",\"keywords\":[\"Certificaci\u00f3n\",\"Prevenci\u00f3n de Adicciones y Salud Mental\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/\",\"name\":\"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/certi13jun.jpg\",\"datePublished\":\"2024-06-13T17:59:27+00:00\",\"dateModified\":\"2024-06-14T18:04:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/certi13jun.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/certi13jun.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/06\\\/13\\\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/","og_locale":"es_MX","og_type":"article","og_title":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 13 de junio de 2024 Se realizaron diversas actividades a favor de la salud de los 330 trabajadores. El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, reconoci\u00f3 a la Empresa ACPS Automotive, como empresa 100 % responsable en la.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2024-06-13T17:59:27+00:00","article_modified_time":"2024-06-14T18:04:44+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental","datePublished":"2024-06-13T17:59:27+00:00","dateModified":"2024-06-14T18:04:44+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/"},"wordCount":301,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg","keywords":["Certificaci\u00f3n","Prevenci\u00f3n de Adicciones y Salud Mental"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/","name":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg","datePublished":"2024-06-13T17:59:27+00:00","dateModified":"2024-06-14T18:04:44+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/06\/certi13jun.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/06\/13\/sesa-certifica-a-acps-automotive-como-empresa-100-responsable-en-prevencion-de-adicciones-y-cuidado-de-la-salud-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"SESA certifica a ACPS Automotive como empresa 100% responsable en prevenci\u00f3n de adicciones y cuidado de la salud mental"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5338"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5337"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}