{"id":5398,"date":"2024-08-22T12:55:49","date_gmt":"2024-08-22T18:55:49","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5398"},"modified":"2024-08-23T12:59:10","modified_gmt":"2024-08-23T18:59:10","slug":"capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/","title":{"rendered":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 22 de agosto de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BOLET\u00cdN SESA 355\/24<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Participaron 100 responsables de establecimientos.\u00a0<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado, capacit\u00f3 en el curso &#8220;Equidad de G\u00e9nero&#8221;, a 100 responsables de Establecimientos Residenciales para el Tratamiento de las Adicciones de los municipios de Col\u00f3n, Corregidora, El Marqu\u00e9s, Ezequiel Montes, Pedro Escobedo, Quer\u00e9taro, San Juan del R\u00edo y Tequisquiapan, as\u00ed como al personal de los Centros Comunitarios de Salud Mental y Adicciones (CECOSAMA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la ceremonia de inauguraci\u00f3n el Comisionado del CECA, Adolfo R\u00edos M\u00e9ndez, destac\u00f3 que el objetivo del curso es analizar las din\u00e1micas de g\u00e9nero que influyen en el tratamiento y la rehabilitaci\u00f3n de las personas con problemas de adicci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se cont\u00f3 con la participaci\u00f3n de la especialista en temas familiares, Paulina Flores y la experta en temas de g\u00e9nero, Mar\u00eda Teresa Ealy D\u00edaz, integrantes de la Fundaci\u00f3n Kooltivo para la Educaci\u00f3n de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La actividad se realiz\u00f3 en las instalaciones del Auditorio Rhino de la Secretar\u00eda de Seguridad Ciudadana y en ella tambi\u00e9n estuvieron presentes:&nbsp; el encargado de despacho de la Secretar\u00eda Ejecutiva de la Defensor\u00eda de los Derechos Humanos de Quer\u00e9taro, V\u00edctor Pernalete Blanco, y el presidente de la Fundaci\u00f3n Kooltivo, Norberto Maldonado Esp\u00edritu.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 22 de agosto de 2024 BOLET\u00cdN SESA 355\/24 El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado, capacit\u00f3 en el curso &#8220;Equidad de G\u00e9nero&#8221;, a 100 responsables de Establecimientos Residenciales para el Tratamiento de las Adicciones de los municipios de Col\u00f3n, Corregidora,.<\/p>\n","protected":false},"author":1,"featured_media":5399,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[175,445],"class_list":["post-5398","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-capacitacion","tag-equidad-de-genero","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 22 de agosto de 2024 BOLET\u00cdN SESA 355\/24 El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado, capacit\u00f3 en el curso &#8220;Equidad de G\u00e9nero&#8221;, a 100 responsables de Establecimientos Residenciales para el Tratamiento de las Adicciones de los municipios de Col\u00f3n, Corregidora,.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-22T18:55:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-23T18:59:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1334\" \/>\n\t<meta property=\"og:image:height\" content=\"1176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0\",\"datePublished\":\"2024-08-22T18:55:49+00:00\",\"dateModified\":\"2024-08-23T18:59:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/\"},\"wordCount\":250,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Equidad-de-Genero-02.jpg\",\"keywords\":[\"Capacitaci\u00f3n\",\"Equidad de G\u00e9nero\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/\",\"name\":\"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Equidad-de-Genero-02.jpg\",\"datePublished\":\"2024-08-22T18:55:49+00:00\",\"dateModified\":\"2024-08-23T18:59:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Equidad-de-Genero-02.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/Equidad-de-Genero-02.jpg\",\"width\":1334,\"height\":1176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/08\\\/22\\\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/","og_locale":"es_MX","og_type":"article","og_title":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 22 de agosto de 2024 BOLET\u00cdN SESA 355\/24 El Consejo Estatal Contra las Adicciones (CECA), de la Secretar\u00eda de Salud (SESA) del estado, capacit\u00f3 en el curso &#8220;Equidad de G\u00e9nero&#8221;, a 100 responsables de Establecimientos Residenciales para el Tratamiento de las Adicciones de los municipios de Col\u00f3n, Corregidora,.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2024-08-22T18:55:49+00:00","article_modified_time":"2024-08-23T18:59:10+00:00","og_image":[{"width":1334,"height":1176,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0","datePublished":"2024-08-22T18:55:49+00:00","dateModified":"2024-08-23T18:59:10+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/"},"wordCount":250,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg","keywords":["Capacitaci\u00f3n","Equidad de G\u00e9nero"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/","name":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0 - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg","datePublished":"2024-08-22T18:55:49+00:00","dateModified":"2024-08-23T18:59:10+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/08\/Equidad-de-Genero-02.jpg","width":1334,"height":1176},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/08\/22\/capacita-sesa-en-equidad-de-genero-a-personal-para-tratamiento-de-adicciones-y-salud-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Capacita SESA en Equidad de G\u00e9nero a personal para tratamiento de adicciones y salud mental\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5398"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5399"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}