{"id":5421,"date":"2024-09-30T15:23:20","date_gmt":"2024-09-30T21:23:20","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5421"},"modified":"2024-09-30T15:23:22","modified_gmt":"2024-09-30T21:23:22","slug":"realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/","title":{"rendered":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br><strong>Se busca fomentar el bienestar f\u00edsico, mental y social de la poblaci\u00f3n, as\u00ed como prevenir el uso de sustancias psicoactivas en ni\u00f1as, ni\u00f1os y juventudes.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 30 de septiembre de 2024<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BOLET\u00cdN SESA 429\/24<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La titular de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, Mar\u00eda Martina P\u00e9rez Rend\u00f3n, encabez\u00f3 la segunda sesi\u00f3n ordinaria de la Mesa Espejo, que tiene como&nbsp; objetivo fomentar el bienestar f\u00edsico, mental y social de la poblaci\u00f3n, as\u00ed como prevenir el uso de sustancias psicoactivas en ni\u00f1as, ni\u00f1os y juventudes, para la construcci\u00f3n de la paz en el marco de los Derechos Humanos y con perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">P\u00e9rez Rend\u00f3n, destac\u00f3 los trabajos realizados en la mesa espejo y la identificaci\u00f3n de las capacidades de atenci\u00f3n en todos los municipios. Detall\u00f3 que la atenci\u00f3n a la salud mental es muy relevante desde todas las vertientes y que CECA, SEJUVE y Educaci\u00f3n, han efectuado varias actividades en este tema, sin embargo es importante fortalecer y multiplicar este trabajo para llegar a mucho m\u00e1s personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo subray\u00f3 la importancia de proporcionar herramientas y destrezas a la sociedad, para que se fortalezca la capacidad de respuesta ante la adversidad, y con ello contar con una poblaci\u00f3n resiliente,&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comisionado del Consejo Estatal Contra las Adicciones (CECA), Adolfo R\u00edos M\u00e9ndez, destac\u00f3 que a trav\u00e9s del trabajo conjunto y el intercambio de ideas, se pueden establecer estrategias efectivas que aseguren un futuro m\u00e1s seguro y saludable para todos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la sesi\u00f3n se cont\u00f3 con la intervenci\u00f3n de personal del Instituto para Prevenir Conductas de Riesgo del municipio de Quer\u00e9taro, que expuso el trabajo realizado a trav\u00e9s del&nbsp; programa de \u201cPsico Educaci\u00f3n Socio-emocional\u201d; de la Secretar\u00eda de la Juventud, con sus actividades dentro de la Comisi\u00f3n de Prevenci\u00f3n y psicoeducaci\u00f3n; y del Instituto Queretano de las Mujeres, el trabajo realizado por la Comisi\u00f3n de Violencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n tambi\u00e9n tuvo la asistencia del subcoordinador General M\u00e9dico de SESEQ, Francisco Rivera Pesquera; el subsecretario de Gobierno, Federico Guillermo de los Cobos y Vega; el director de Centro Estatal de Salud Mental, Sergio Aceves Guzm\u00e1n; los directores de la Jurisdicciones Sanitarias 1, 2, 3 y 4.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed como integrantes de los Centros de Integraci\u00f3n Juvenil, coordinadores de los Comit\u00e9s Municipales Contra las Adicciones, Secretar\u00eda de la Juventud, Secretar\u00eda de Educaci\u00f3n, Secretar\u00eda de Seguridad Ciudadana, del Instituto Mexicano del Seguro Social, entre otras instancias de gobierno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se busca fomentar el bienestar f\u00edsico, mental y social de la poblaci\u00f3n, as\u00ed como prevenir el uso de sustancias psicoactivas en ni\u00f1as, ni\u00f1os y juventudes. Quer\u00e9taro, Qro., 30 de septiembre de 2024 BOLET\u00cdN SESA 429\/24 La titular de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, Mar\u00eda Martina P\u00e9rez.<\/p>\n","protected":false},"author":1,"featured_media":5422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[450,451,144],"class_list":["post-5421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-bienestar-fisico","tag-mental","tag-prevencion-2","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Se busca fomentar el bienestar f\u00edsico, mental y social de la poblaci\u00f3n, as\u00ed como prevenir el uso de sustancias psicoactivas en ni\u00f1as, ni\u00f1os y juventudes. Quer\u00e9taro, Qro., 30 de septiembre de 2024 BOLET\u00cdN SESA 429\/24 La titular de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, Mar\u00eda Martina P\u00e9rez.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-30T21:23:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-30T21:23:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1382\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo\",\"datePublished\":\"2024-09-30T21:23:20+00:00\",\"dateModified\":\"2024-09-30T21:23:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/\"},\"wordCount\":452,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MesaEspejo.jpg\",\"keywords\":[\"bienestar f\u00edsico\",\"mental\",\"Prevenci\u00f3n\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/\",\"name\":\"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MesaEspejo.jpg\",\"datePublished\":\"2024-09-30T21:23:20+00:00\",\"dateModified\":\"2024-09-30T21:23:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MesaEspejo.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/MesaEspejo.jpg\",\"width\":1382,\"height\":886},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/09\\\/30\\\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/","og_locale":"es_MX","og_type":"article","og_title":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO","og_description":"Se busca fomentar el bienestar f\u00edsico, mental y social de la poblaci\u00f3n, as\u00ed como prevenir el uso de sustancias psicoactivas en ni\u00f1as, ni\u00f1os y juventudes. Quer\u00e9taro, Qro., 30 de septiembre de 2024 BOLET\u00cdN SESA 429\/24 La titular de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, Mar\u00eda Martina P\u00e9rez.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2024-09-30T21:23:20+00:00","article_modified_time":"2024-09-30T21:23:22+00:00","og_image":[{"width":1382,"height":886,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo","datePublished":"2024-09-30T21:23:20+00:00","dateModified":"2024-09-30T21:23:22+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/"},"wordCount":452,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg","keywords":["bienestar f\u00edsico","mental","Prevenci\u00f3n"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/","name":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg","datePublished":"2024-09-30T21:23:20+00:00","dateModified":"2024-09-30T21:23:22+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/09\/MesaEspejo.jpg","width":1382,"height":886},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/09\/30\/realiza-sesa-segunda-sesion-ordinaria-de-la-mesa-espejo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Realiza SESA segunda sesi\u00f3n ordinaria de la Mesa Espejo"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5421"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5421\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5422"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}