{"id":5443,"date":"2024-10-29T18:08:06","date_gmt":"2024-10-30T00:08:06","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5443"},"modified":"2024-10-29T18:08:08","modified_gmt":"2024-10-30T00:08:08","slug":"lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/","title":{"rendered":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 29 de octubre de 2024.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTONOTA SESA 475\/24<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personal del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, realiz\u00f3 la Jornada Comunitaria de prevenci\u00f3n de adicciones y cuidado de la salud mental en la colonia Las Azucenas, del municipio de Quer\u00e9taro, con el objetivo de fortalecer la cohesi\u00f3n social, facilitar la reinserci\u00f3n social de pacientes de centros de rehabilitaci\u00f3n, as\u00ed como contribuir a la recuperaci\u00f3n de espacios p\u00fablicos que beneficien a toda la comunidad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En dicha actividad participaron un total de 60 personas del grupo VoluntadEs, integrado por personal del CECA, pacientes del centro de rehabilitaci\u00f3n KOI, trabajadores del \u00e1rea de parques y jardines, y de personas en conflicto con la ley que se encuentran en tratamiento en el Centro Comunitario de Salud Mental y Adicciones Santa Mar\u00eda Magdalena. La actividad consisti\u00f3 en el desmalezado y plantaci\u00f3n de 18 \u00e1rboles, as\u00ed como la pinta de paredes, todo en el \u00e1rea verde de la Colonia Las Azucenas. Asimismo, se brind\u00f3 capacitaci\u00f3n sobre prevenci\u00f3n de la depresi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 29 de octubre de 2024. FOTONOTA SESA 475\/24 Personal del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, realiz\u00f3 la Jornada Comunitaria de prevenci\u00f3n de adicciones y cuidado de la salud mental en la colonia Las Azucenas, del municipio de.<\/p>\n","protected":false},"author":1,"featured_media":5444,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[391,302,203,38],"class_list":["post-5443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-jornada-comunitaria","tag-prevencion-de-adicciones","tag-queretaro","tag-salud-mental","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 29 de octubre de 2024. FOTONOTA SESA 475\/24 Personal del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, realiz\u00f3 la Jornada Comunitaria de prevenci\u00f3n de adicciones y cuidado de la salud mental en la colonia Las Azucenas, del municipio de.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-30T00:08:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-30T00:08:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas\",\"datePublished\":\"2024-10-30T00:08:06+00:00\",\"dateModified\":\"2024-10-30T00:08:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/\"},\"wordCount\":204,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.jpg\",\"keywords\":[\"Jornada comunitaria\",\"Prevenci\u00f3n de Adicciones\",\"Quer\u00e9taro\",\"SALUD MENTAL\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/\",\"name\":\"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.jpg\",\"datePublished\":\"2024-10-30T00:08:06+00:00\",\"dateModified\":\"2024-10-30T00:08:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/1.jpg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2024\\\/10\\\/29\\\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/","og_locale":"es_MX","og_type":"article","og_title":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 29 de octubre de 2024. FOTONOTA SESA 475\/24 Personal del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, realiz\u00f3 la Jornada Comunitaria de prevenci\u00f3n de adicciones y cuidado de la salud mental en la colonia Las Azucenas, del municipio de.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2024-10-30T00:08:06+00:00","article_modified_time":"2024-10-30T00:08:08+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas","datePublished":"2024-10-30T00:08:06+00:00","dateModified":"2024-10-30T00:08:08+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/"},"wordCount":204,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg","keywords":["Jornada comunitaria","Prevenci\u00f3n de Adicciones","Quer\u00e9taro","SALUD MENTAL"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/","name":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg","datePublished":"2024-10-30T00:08:06+00:00","dateModified":"2024-10-30T00:08:08+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2024\/10\/1.jpg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2024\/10\/29\/lleva-ceca-jornada-comunitaria-en-prevencion-de-adicciones-y-cuidado-de-salud-mental-a-las-azucenas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Lleva CECA Jornada Comunitaria en prevenci\u00f3n de adicciones y cuidado de salud mental a Las Azucenas"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5443"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5444"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}