{"id":5546,"date":"2025-03-19T10:47:02","date_gmt":"2025-03-19T16:47:02","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5546"},"modified":"2025-03-20T10:47:56","modified_gmt":"2025-03-20T16:47:56","slug":"capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/","title":{"rendered":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 19 de marzo de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTONOTA SESA 131\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personal especializado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, capacit\u00f3 en Prevenci\u00f3n de Adicciones y Salud Mental, a 528 operadores y personal administrativo, (299 hombres y 234 mujeres), de la Agencia de Movilidad del Estado de Quer\u00e9taro (AMEQ)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo es proporcionar herramientas y conocimientos para identificar posibles signos de adicciones, as\u00ed como estrategias de intervenci\u00f3n y apoyo para mantener el bienestar psicol\u00f3gico en las y los trabajadores. Para ello se realizaron 19 conferencias en donde se abordaron temas cruciales sobre la prevenci\u00f3n de adicciones y la promoci\u00f3n de la salud mental en el entorno laboral.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 19 de marzo de 2025 FOTONOTA SESA 131\/25 Personal especializado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, capacit\u00f3 en Prevenci\u00f3n de Adicciones y Salud Mental, a 528 operadores y personal administrativo, (299 hombres y 234 mujeres), de la.<\/p>\n","protected":false},"author":1,"featured_media":5547,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[478,34,302,38],"class_list":["post-5546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-ameq","tag-prevencion","tag-prevencion-de-adicciones","tag-salud-mental","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 19 de marzo de 2025 FOTONOTA SESA 131\/25 Personal especializado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, capacit\u00f3 en Prevenci\u00f3n de Adicciones y Salud Mental, a 528 operadores y personal administrativo, (299 hombres y 234 mujeres), de la.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T16:47:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-20T16:47:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1204\" \/>\n\t<meta property=\"og:image:height\" content=\"883\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ\",\"datePublished\":\"2025-03-19T16:47:02+00:00\",\"dateModified\":\"2025-03-20T16:47:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/\"},\"wordCount\":133,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg\",\"keywords\":[\"AMEQ\",\"PREVENCI\u00d3N\",\"Prevenci\u00f3n de Adicciones\",\"SALUD MENTAL\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/\",\"name\":\"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg\",\"datePublished\":\"2025-03-19T16:47:02+00:00\",\"dateModified\":\"2025-03-20T16:47:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg\",\"width\":1204,\"height\":883},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/19\\\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/","og_locale":"es_MX","og_type":"article","og_title":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 19 de marzo de 2025 FOTONOTA SESA 131\/25 Personal especializado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado de Quer\u00e9taro, capacit\u00f3 en Prevenci\u00f3n de Adicciones y Salud Mental, a 528 operadores y personal administrativo, (299 hombres y 234 mujeres), de la.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-03-19T16:47:02+00:00","article_modified_time":"2025-03-20T16:47:56+00:00","og_image":[{"width":1204,"height":883,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ","datePublished":"2025-03-19T16:47:02+00:00","dateModified":"2025-03-20T16:47:56+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/"},"wordCount":133,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg","keywords":["AMEQ","PREVENCI\u00d3N","Prevenci\u00f3n de Adicciones","SALUD MENTAL"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/","name":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg","datePublished":"2025-03-19T16:47:02+00:00","dateModified":"2025-03-20T16:47:56+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/71_273_47353_1957118092_6_1903_SESA_AMEQ.jpg","width":1204,"height":883},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/19\/capacita-sesa-en-prevencion-de-adicciones-y-salud-mental-a-personal-de-la-ameq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Capacita SESA en prevenci\u00f3n de adicciones y salud mental a personal de la AMEQ"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5546"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5546\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5547"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}