{"id":5550,"date":"2025-03-25T21:24:34","date_gmt":"2025-03-26T03:24:34","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5550"},"modified":"2025-03-25T21:24:35","modified_gmt":"2025-03-26T03:24:35","slug":"participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/","title":{"rendered":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 25 de marzo de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTONOTA SESA 143\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un esfuerzo por fortalecer la prevenci\u00f3n de adicciones y promover el bienestar de las familias, el comisionado del Consejo Estatal contra las Adicciones de la Secretar\u00eda de Salud (SESA) del estado, Adolfo R\u00edos M\u00e9ndez, particip\u00f3 en el Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen, del \u00c1rea Quer\u00e9taro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su intervenci\u00f3n, el Comisionado subray\u00f3 que las adicciones son una enfermedad que requieren tratamiento profesional y que es de vital importancia el apoyo de la familia ya que combinado con la orientaci\u00f3n de grupos como Al-Anon y Alateen, es clave para enfrentar el impacto de la adicci\u00f3n y construir un camino hacia el control de esta. &nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 25 de marzo de 2025 FOTONOTA SESA 143\/25 En un esfuerzo por fortalecer la prevenci\u00f3n de adicciones y promover el bienestar de las familias, el comisionado del Consejo Estatal contra las Adicciones de la Secretar\u00eda de Salud (SESA) del estado, Adolfo R\u00edos M\u00e9ndez, particip\u00f3 en el Simposium para.<\/p>\n","protected":false},"author":1,"featured_media":5551,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-5550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 25 de marzo de 2025 FOTONOTA SESA 143\/25 En un esfuerzo por fortalecer la prevenci\u00f3n de adicciones y promover el bienestar de las familias, el comisionado del Consejo Estatal contra las Adicciones de la Secretar\u00eda de Salud (SESA) del estado, Adolfo R\u00edos M\u00e9ndez, particip\u00f3 en el Simposium para.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-26T03:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-26T03:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen\",\"datePublished\":\"2025-03-26T03:24:34+00:00\",\"dateModified\":\"2025-03-26T03:24:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/\"},\"wordCount\":138,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-scaled.jpg\",\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/\",\"name\":\"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-scaled.jpg\",\"datePublished\":\"2025-03-26T03:24:34+00:00\",\"dateModified\":\"2025-03-26T03:24:35+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/10-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/03\\\/25\\\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/","og_locale":"es_MX","og_type":"article","og_title":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 25 de marzo de 2025 FOTONOTA SESA 143\/25 En un esfuerzo por fortalecer la prevenci\u00f3n de adicciones y promover el bienestar de las familias, el comisionado del Consejo Estatal contra las Adicciones de la Secretar\u00eda de Salud (SESA) del estado, Adolfo R\u00edos M\u00e9ndez, particip\u00f3 en el Simposium para.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-03-26T03:24:34+00:00","article_modified_time":"2025-03-26T03:24:35+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen","datePublished":"2025-03-26T03:24:34+00:00","dateModified":"2025-03-26T03:24:35+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/"},"wordCount":138,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg","articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/","name":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg","datePublished":"2025-03-26T03:24:34+00:00","dateModified":"2025-03-26T03:24:35+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/03\/10-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/03\/25\/participa-ceca-en-simposium-para-profesionales-de-grupos-de-familia-al-anon-y-alateen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Participa CECA en Simposium para Profesionales de Grupos de Familia Al-Anon y Alateen"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5550"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5551"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}