{"id":5564,"date":"2025-04-10T10:49:49","date_gmt":"2025-04-10T16:49:49","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5564"},"modified":"2025-04-11T10:51:37","modified_gmt":"2025-04-11T16:51:37","slug":"lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/","title":{"rendered":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tolim\u00e1n, Qro., 10 de abril de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTONOTA SESA 176\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de brindar herramientas informativas y emocionales para la toma de decisiones saludables, fomentando estilos de vida libres de adicciones y fortaleciendo su bienestar mental y emocional de la comunidad, las y los profesionales del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud, llev\u00f3 prevenci\u00f3n de adicciones, conductas de riesgo y salud mental, a la comunidad estudiantil del Colegio de Bachilleres del Estado de Quer\u00e9taro Plantel 6 Tolim\u00e1n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se brindaron siete conferencias y se capacit\u00f3 a un total de 253&nbsp; personas, entre alumnas y alumnos, docentes, padres y madres de familia, en donde se abordaron los temas de: Diez recomendaciones para prevenir que tus hijas e hijos consuman drogas, Primeros Auxilios Psicol\u00f3gicos,&nbsp; Manual de Consulta Psicoeducativa y Prevenci\u00f3n de adicciones y atenci\u00f3n a la salud mental.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tolim\u00e1n, Qro., 10 de abril de 2025 FOTONOTA SESA 176\/25 Con el objetivo de brindar herramientas informativas y emocionales para la toma de decisiones saludables, fomentando estilos de vida libres de adicciones y fortaleciendo su bienestar mental y emocional de la comunidad, las y los profesionales del Consejo Estatal Contra.<\/p>\n","protected":false},"author":1,"featured_media":5565,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[302,38,193],"class_list":["post-5564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-prevencion-de-adicciones","tag-salud-mental","tag-toliman","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Tolim\u00e1n, Qro., 10 de abril de 2025 FOTONOTA SESA 176\/25 Con el objetivo de brindar herramientas informativas y emocionales para la toma de decisiones saludables, fomentando estilos de vida libres de adicciones y fortaleciendo su bienestar mental y emocional de la comunidad, las y los profesionales del Consejo Estatal Contra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T16:49:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T16:51:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"966\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0\",\"datePublished\":\"2025-04-10T16:49:49+00:00\",\"dateModified\":\"2025-04-11T16:51:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/\"},\"wordCount\":160,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg\",\"keywords\":[\"Prevenci\u00f3n de Adicciones\",\"SALUD MENTAL\",\"Tolim\u00e1n\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/\",\"name\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg\",\"datePublished\":\"2025-04-10T16:49:49+00:00\",\"dateModified\":\"2025-04-11T16:51:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg\",\"width\":960,\"height\":966},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/10\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/","og_locale":"es_MX","og_type":"article","og_title":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO","og_description":"Tolim\u00e1n, Qro., 10 de abril de 2025 FOTONOTA SESA 176\/25 Con el objetivo de brindar herramientas informativas y emocionales para la toma de decisiones saludables, fomentando estilos de vida libres de adicciones y fortaleciendo su bienestar mental y emocional de la comunidad, las y los profesionales del Consejo Estatal Contra.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-04-10T16:49:49+00:00","article_modified_time":"2025-04-11T16:51:37+00:00","og_image":[{"width":960,"height":966,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0","datePublished":"2025-04-10T16:49:49+00:00","dateModified":"2025-04-11T16:51:37+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/"},"wordCount":160,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg","keywords":["Prevenci\u00f3n de Adicciones","SALUD MENTAL","Tolim\u00e1n"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/","name":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0 - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg","datePublished":"2025-04-10T16:49:49+00:00","dateModified":"2025-04-11T16:51:37+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/WhatsApp-Image-2025-04-01-at-11.14.22-AM.jpeg","width":960,"height":966},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/10\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-toliman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Tolim\u00e1n\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5564"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5565"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}