{"id":5575,"date":"2025-04-26T19:49:18","date_gmt":"2025-04-27T01:49:18","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5575"},"modified":"2025-04-28T19:58:40","modified_gmt":"2025-04-29T01:58:40","slug":"lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/","title":{"rendered":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Marqu\u00e9s, Qro., 26 de abril de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTONOTA SESA 203\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Personal del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado, llev\u00f3 conferencia en \u201cPrevenci\u00f3n de Adicciones y Salud Mental\u201d, a 35 l\u00edderes estudiantiles de Ciencias de la Salud de la Universidad An\u00e1huac, con el objetivo de fortalecer de proporcionar habilidades y destrezas que les permitan actuar como agentes de cambio dentro de sus comunidades, promoviendo estilos de vida saludables y compromiso profesional con el bienestar integral.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El comisionado del CECA, Adolfo R\u00edos M\u00e9ndez, expres\u00f3 que desde el Consejo Estatal contra las Adicciones, se realizan acciones a favor de la salud mental en diferentes \u00e1mbitos de forma colaborativa para beneficio de la poblaci\u00f3n. La conferencia fue desarrollada por Iker Vega, quien comparti\u00f3 la importancia de pedir ayuda al detectar un problema de adicci\u00f3n y salud mental. En el evento se cont\u00f3 con la presencia de la coordinadora del Programa de Liderazgo en Ciencias de la Salud, Mariana Garrido Rocha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Marqu\u00e9s, Qro., 26 de abril de 2025 FOTONOTA SESA 203\/25 Personal del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado, llev\u00f3 conferencia en \u201cPrevenci\u00f3n de Adicciones y Salud Mental\u201d, a 35 l\u00edderes estudiantiles de Ciencias de la Salud de la Universidad An\u00e1huac, con.<\/p>\n","protected":false},"author":1,"featured_media":5576,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[471,302,38,484],"class_list":["post-5575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-anahuac","tag-prevencion-de-adicciones","tag-salud-mental","tag-universidad","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"El Marqu\u00e9s, Qro., 26 de abril de 2025 FOTONOTA SESA 203\/25 Personal del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado, llev\u00f3 conferencia en \u201cPrevenci\u00f3n de Adicciones y Salud Mental\u201d, a 35 l\u00edderes estudiantiles de Ciencias de la Salud de la Universidad An\u00e1huac, con.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-27T01:49:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-29T01:58:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac\",\"datePublished\":\"2025-04-27T01:49:18+00:00\",\"dateModified\":\"2025-04-29T01:58:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/\"},\"wordCount\":190,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/photo_4927255957818420748_y.jpg\",\"keywords\":[\"ANAHUAC\",\"Prevenci\u00f3n de Adicciones\",\"SALUD MENTAL\",\"Universidad\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/\",\"name\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/photo_4927255957818420748_y.jpg\",\"datePublished\":\"2025-04-27T01:49:18+00:00\",\"dateModified\":\"2025-04-29T01:58:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/photo_4927255957818420748_y.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/photo_4927255957818420748_y.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/04\\\/26\\\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/","og_locale":"es_MX","og_type":"article","og_title":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO","og_description":"El Marqu\u00e9s, Qro., 26 de abril de 2025 FOTONOTA SESA 203\/25 Personal del Consejo Estatal Contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA) del estado, llev\u00f3 conferencia en \u201cPrevenci\u00f3n de Adicciones y Salud Mental\u201d, a 35 l\u00edderes estudiantiles de Ciencias de la Salud de la Universidad An\u00e1huac, con.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-04-27T01:49:18+00:00","article_modified_time":"2025-04-29T01:58:40+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac","datePublished":"2025-04-27T01:49:18+00:00","dateModified":"2025-04-29T01:58:40+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/"},"wordCount":190,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg","keywords":["ANAHUAC","Prevenci\u00f3n de Adicciones","SALUD MENTAL","Universidad"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/","name":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg","datePublished":"2025-04-27T01:49:18+00:00","dateModified":"2025-04-29T01:58:40+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/04\/photo_4927255957818420748_y.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/04\/26\/lleva-ceca-prevencion-de-adicciones-y-salud-mental-a-ciencias-de-la-salud-de-la-universidad-anahuac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Lleva CECA prevenci\u00f3n de adicciones y salud mental a Ciencias de la Salud de la Universidad An\u00e1huac"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5575"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5576"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}