{"id":5633,"date":"2025-08-22T14:23:06","date_gmt":"2025-08-22T20:23:06","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5633"},"modified":"2025-08-25T14:24:43","modified_gmt":"2025-08-25T20:24:43","slug":"capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/","title":{"rendered":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Quer\u00e9taro, Qro., 22 de agosto de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>BOLET\u00cdN SESA 384\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00a0<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asisten 100 directores y responsables de centros de rehabilitaci\u00f3n.<\/li>\n\n\n\n<li>Se les capacita en \u201cAcompa\u00f1amiento Humano desde la Inteligencia Artificial\u201d.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El Comisionado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA), Adolfo R\u00edos M\u00e9ndez, encabez\u00f3 la capacitaci\u00f3n \u201cAcompa\u00f1amiento Humano desde la Inteligencia Artificial\u201d, dirigida a 100 directores y servidores de centros de rehabilitaci\u00f3n del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su intervenci\u00f3n, R\u00edos M\u00e9ndez destac\u00f3 que el prop\u00f3sito de esta iniciativa es acercar herramientas tecnol\u00f3gicas innovadoras que fortalezcan el trabajo terap\u00e9utico, impulsando procesos de atenci\u00f3n y rehabilitaci\u00f3n m\u00e1s eficaces para las personas con problemas de adicciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Subray\u00f3 que la Inteligencia Artificial no sustituye el acompa\u00f1amiento humano, sino que lo complementa, al permitir anticipar riesgos, mejorar la organizaci\u00f3n de los tratamientos y reforzar la labor de los equipos que&nbsp; de forma diaria brindan apoyo a quienes lo requieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, el funcionario estatal resalt\u00f3 que esta capacitaci\u00f3n busca fomentar la detecci\u00f3n temprana de riesgos, fortalecer el seguimiento terap\u00e9utico y promover la innovaci\u00f3n tecnol\u00f3gica como una aliada estrat\u00e9gica en la atenci\u00f3n integral y la prevenci\u00f3n de las adicciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La jornada se llev\u00f3 a cabo en coordinaci\u00f3n con Centros de Integraci\u00f3n Juvenil y el Patronato del Club de Leones de Quer\u00e9taro, con la participaci\u00f3n del psic\u00f3logo H\u00e9ctor Mart\u00edn Hern\u00e1ndez Casta\u00f1\u00f3n, quien estuvo a cargo de la ponencia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quer\u00e9taro, Qro., 22 de agosto de 2025 BOLET\u00cdN SESA 384\/25 \u00a0 El Comisionado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA), Adolfo R\u00edos M\u00e9ndez, encabez\u00f3 la capacitaci\u00f3n \u201cAcompa\u00f1amiento Humano desde la Inteligencia Artificial\u201d, dirigida a 100 directores y servidores de centros de rehabilitaci\u00f3n del estado..<\/p>\n","protected":false},"author":1,"featured_media":5634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[462,171,491],"class_list":["post-5633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-462","tag-establecimientos-residenciales-de-atencion-y-tratamiento-de-adicciones","tag-tratamiento-de-adicciones","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Quer\u00e9taro, Qro., 22 de agosto de 2025 BOLET\u00cdN SESA 384\/25 \u00a0 El Comisionado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA), Adolfo R\u00edos M\u00e9ndez, encabez\u00f3 la capacitaci\u00f3n \u201cAcompa\u00f1amiento Humano desde la Inteligencia Artificial\u201d, dirigida a 100 directores y servidores de centros de rehabilitaci\u00f3n del estado..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-22T20:23:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T20:24:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1560\" \/>\n\t<meta property=\"og:image:height\" content=\"1040\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones\",\"datePublished\":\"2025-08-22T20:23:06+00:00\",\"dateModified\":\"2025-08-25T20:24:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/\"},\"wordCount\":268,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dirs_establecimientos.jpg\",\"keywords\":[\"2025\",\"Establecimientos Residenciales de Atenci\u00f3n y Tratamiento de Adicciones\",\"Tratamiento de Adicciones\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/\",\"name\":\"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dirs_establecimientos.jpg\",\"datePublished\":\"2025-08-22T20:23:06+00:00\",\"dateModified\":\"2025-08-25T20:24:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dirs_establecimientos.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/dirs_establecimientos.jpg\",\"width\":1560,\"height\":1040},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/08\\\/22\\\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/","og_locale":"es_MX","og_type":"article","og_title":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO","og_description":"Quer\u00e9taro, Qro., 22 de agosto de 2025 BOLET\u00cdN SESA 384\/25 \u00a0 El Comisionado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA), Adolfo R\u00edos M\u00e9ndez, encabez\u00f3 la capacitaci\u00f3n \u201cAcompa\u00f1amiento Humano desde la Inteligencia Artificial\u201d, dirigida a 100 directores y servidores de centros de rehabilitaci\u00f3n del estado..","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-08-22T20:23:06+00:00","article_modified_time":"2025-08-25T20:24:43+00:00","og_image":[{"width":1560,"height":1040,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones","datePublished":"2025-08-22T20:23:06+00:00","dateModified":"2025-08-25T20:24:43+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/"},"wordCount":268,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg","keywords":["2025","Establecimientos Residenciales de Atenci\u00f3n y Tratamiento de Adicciones","Tratamiento de Adicciones"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/","name":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg","datePublished":"2025-08-22T20:23:06+00:00","dateModified":"2025-08-25T20:24:43+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/08\/dirs_establecimientos.jpg","width":1560,"height":1040},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/08\/22\/capacita-ceca-a-directores-de-establecimientos-residenciales-para-el-tratamiento-de-adicciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Capacita CECA a directores de establecimientos residenciales para el tratamiento de adicciones"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5633"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5633\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5634"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}