{"id":5638,"date":"2025-09-04T10:56:07","date_gmt":"2025-09-04T16:56:07","guid":{"rendered":"https:\/\/gobqro.gob.mx\/cecaqro\/?p=5638"},"modified":"2025-09-08T11:00:56","modified_gmt":"2025-09-08T17:00:56","slug":"se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra","status":"publish","type":"post","link":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/","title":{"rendered":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jalpan de Serra, Qro., 4 de septiembre de 2025<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>FOTO NOTA SESA 406\/25<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con el objetivo de fortalecer las acciones de prevenci\u00f3n y atenci\u00f3n de las adicciones, se realiz\u00f3 la instalaci\u00f3n del Comit\u00e9 Municipal contra las Adicciones (COMCA) de Jalpan de Serra, encabezada por el comisionado del Consejo Estatal contra las Adicciones (CECA) de la Secretar\u00eda de Salud (SESA), Adolfo R\u00edos M\u00e9ndez y el presidente municipal Rub\u00e9n Hern\u00e1ndez Robles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la ceremonia, ambos funcionarios destacaron que con el COMCA se fortalecen las acciones de prevenci\u00f3n, atenci\u00f3n y coordinaci\u00f3n, generando beneficios directos para la sociedad, al promover la salud y el bienestar; para el municipio, al contar con m\u00e1s herramientas en el cuidado de la poblaci\u00f3n; y para el CECA, al consolidar una red m\u00e1s cercana y efectiva con cada comunidad.&nbsp; Con estas acciones se avanza en la construcci\u00f3n de una sociedad informada y protegida frente a las adicciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jalpan de Serra, Qro., 4 de septiembre de 2025 FOTO NOTA SESA 406\/25 Con el objetivo de fortalecer las acciones de prevenci\u00f3n y atenci\u00f3n de las adicciones, se realiz\u00f3 la instalaci\u00f3n del Comit\u00e9 Municipal contra las Adicciones (COMCA) de Jalpan de Serra, encabezada por el comisionado del Consejo Estatal contra.<\/p>\n","protected":false},"author":1,"featured_media":5639,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[37,494,188],"class_list":["post-5638","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boletines","tag-adicciones","tag-comite-municipal","tag-jalpan-de-serra","no-social-count","single-post-item mb40"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:description\" content=\"Jalpan de Serra, Qro., 4 de septiembre de 2025 FOTO NOTA SESA 406\/25 Con el objetivo de fortalecer las acciones de prevenci\u00f3n y atenci\u00f3n de las adicciones, se realiz\u00f3 la instalaci\u00f3n del Comit\u00e9 Municipal contra las Adicciones (COMCA) de Jalpan de Serra, encabezada por el comisionado del Consejo Estatal contra.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T16:56:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-08T17:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"935\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MasCK\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MasCK\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/\"},\"author\":{\"name\":\"MasCK\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"headline\":\"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra\",\"datePublished\":\"2025-09-04T16:56:07+00:00\",\"dateModified\":\"2025-09-08T17:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/\"},\"wordCount\":172,\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/comiteMunicipal.jpg\",\"keywords\":[\"ADICCIONES\",\"Comit\u00e9 Municipal\",\"Jalpan de Serra\"],\"articleSection\":[\"BOLETINES\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/\",\"name\":\"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/comiteMunicipal.jpg\",\"datePublished\":\"2025-09-04T16:56:07+00:00\",\"dateModified\":\"2025-09-08T17:00:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/comiteMunicipal.jpg\",\"contentUrl\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/comiteMunicipal.jpg\",\"width\":935,\"height\":701},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/2025\\\/09\\\/04\\\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#\\\/schema\\\/person\\\/72c88ebcabc83c5cc9aea1281ea5ecf5\",\"name\":\"MasCK\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g\",\"caption\":\"MasCK\"},\"sameAs\":[\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\"],\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/author\\\/masck\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/","og_locale":"es_MX","og_type":"article","og_title":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO","og_description":"Jalpan de Serra, Qro., 4 de septiembre de 2025 FOTO NOTA SESA 406\/25 Con el objetivo de fortalecer las acciones de prevenci\u00f3n y atenci\u00f3n de las adicciones, se realiz\u00f3 la instalaci\u00f3n del Comit\u00e9 Municipal contra las Adicciones (COMCA) de Jalpan de Serra, encabezada por el comisionado del Consejo Estatal contra.","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/","og_site_name":"CECA QUER\u00c9TARO","article_published_time":"2025-09-04T16:56:07+00:00","article_modified_time":"2025-09-08T17:00:56+00:00","og_image":[{"width":935,"height":701,"url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg","type":"image\/jpeg"}],"author":"MasCK","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MasCK","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#article","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/"},"author":{"name":"MasCK","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"headline":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra","datePublished":"2025-09-04T16:56:07+00:00","dateModified":"2025-09-08T17:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/"},"wordCount":172,"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg","keywords":["ADICCIONES","Comit\u00e9 Municipal","Jalpan de Serra"],"articleSection":["BOLETINES"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/","name":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#primaryimage"},"image":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#primaryimage"},"thumbnailUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg","datePublished":"2025-09-04T16:56:07+00:00","dateModified":"2025-09-08T17:00:56+00:00","author":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#primaryimage","url":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg","contentUrl":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-content\/uploads\/2025\/09\/comiteMunicipal.jpg","width":935,"height":701},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/2025\/09\/04\/se-instala-comite-municipal-contra-las-adicciones-en-jalpan-de-serra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"Se Instala Comit\u00e9 Municipal contra las Adicciones en Jalpan de Serra"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#\/schema\/person\/72c88ebcabc83c5cc9aea1281ea5ecf5","name":"MasCK","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00802ca4a66d8feb24d26644abfdb80edd1a239d9fe80e4695b2f118020c55fb?s=96&d=mm&r=g","caption":"MasCK"},"sameAs":["https:\/\/gobqro.gob.mx\/cecaqro"],"url":"https:\/\/gobqro.gob.mx\/cecaqro\/author\/masck\/"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5638","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/comments?post=5638"}],"version-history":[{"count":0,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts\/5638\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media\/5639"}],"wp:attachment":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/media?parent=5638"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/categories?post=5638"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags?post=5638"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}