{"id":430,"count":1,"description":"","link":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas","slug":"dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/\" \/>\n<meta property=\"og:site_name\" content=\"CECA QUER\u00c9TARO\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/\",\"name\":\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/tag\\\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/#website\",\"url\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/\",\"name\":\"CECA QUER\u00c9TARO\",\"description\":\"Consejo Estatal Contra las Adicciones\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gobqro.gob.mx\\\/cecaqro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","og_locale":"es_MX","og_type":"article","og_title":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO","og_url":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","og_site_name":"CECA QUER\u00c9TARO","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","url":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/","name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas archivos - CECA QUER\u00c9TARO","isPartOf":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website"},"breadcrumb":{"@id":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/tag\/dia-internacional-de-la-lucha-contra-el-uso-indebido-y-el-trafico-ilicito-de-drogas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/gobqro.gob.mx\/cecaqro\/"},{"@type":"ListItem","position":2,"name":"D\u00eda Internacional de la Lucha contra el Uso Indebido y el Tr\u00e1fico Il\u00edcito de Drogas"}]},{"@type":"WebSite","@id":"https:\/\/gobqro.gob.mx\/cecaqro\/#website","url":"https:\/\/gobqro.gob.mx\/cecaqro\/","name":"CECA QUER\u00c9TARO","description":"Consejo Estatal Contra las Adicciones","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gobqro.gob.mx\/cecaqro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags\/430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/gobqro.gob.mx\/cecaqro\/wp-json\/wp\/v2\/posts?tags=430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}